{"id":4009,"date":"2025-05-05T13:12:24","date_gmt":"2025-05-05T13:12:24","guid":{"rendered":"https:\/\/ombrasole.com\/?p=4009"},"modified":"2025-05-05T14:42:16","modified_gmt":"2025-05-05T14:42:16","slug":"capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec","status":"publish","type":"post","link":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/","title":{"rendered":"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec"},"content":{"rendered":"\n<p>Vous souhaitez transformer la terrasse de votre entreprise en un espace \u00e9l\u00e9gant, confortable et prot\u00e9g\u00e9 tout au long de l&rsquo;ann\u00e9e?\u00a0 <a href=\"https:\/\/ombrasole.com\/commercial\/terrace-awnings\/\">La pergola commerciale Capriccio<\/a>, fabriqu\u00e9e \u00e0 Montr\u00e9al, est la meilleure solution pour les restaurants, les h\u00f4tels, les clubs de golf et les salles de r\u00e9ception qui souhaitent offrir une exp\u00e9rience ext\u00e9rieure de qualit\u00e9 sup\u00e9rieure sans se soucier de la m\u00e9t\u00e9o. Plus qu&rsquo;un simple auvent, il s&rsquo;agit d&rsquo;une structure au design sophistiqu\u00e9 qui transforme tout espace ext\u00e9rieur en une extension fonctionnelle et accueillante de votre entreprise.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>3 raisons pour lesquelles Capriccio est le meilleur choix pour votre terrasse commerciale<\/strong><\/h2>\n\n\n\n<p><strong>1. L&rsquo;\u00e9l\u00e9gance et la solidit\u00e9 qui rehaussent l&rsquo;image de votre entreprise<\/strong><\/p>\n\n\n\n<p>La <a href=\"https:\/\/ombrasole.com\/commercial\/terrace-awnings\/\">pergola Capriccio<\/a> est construite en aluminium extrud\u00e9, ce qui lui permet d&rsquo;avoir un design moderne et une structure robuste en m\u00eame temps. Sa toile vinyle Serge Ferrari haut de gamme et imperm\u00e9able assure une protection durable contre le soleil, la pluie et les vents violents pendant au moins 15 ans, r\u00e9affirmant ainsi sa qualit\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"902\" height=\"678\" src=\"https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image.png\" alt=\"Pergola r\u00e9tractable Capriccio install\u00e9e sur la terrasse d'un restaurant \u00e0 Montr\u00e9al.\" class=\"wp-image-4010\" srcset=\"https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image.png 902w, https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image-300x225.png 300w, https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image-768x577.png 768w\" sizes=\"auto, (max-width: 902px) 100vw, 902px\" \/><\/figure>\n\n\n\n<p><strong>2. Technologie intelligente avec gestion \u00e0 distance<\/strong><\/p>\n\n\n\n<p>Chaque section (jusqu&rsquo;\u00e0 14 pieds) est actionn\u00e9e ind\u00e9pendamment par un moteur SOMFY, qui peut \u00eatre contr\u00f4l\u00e9 \u00e0 distance avec une t\u00e9l\u00e9commande ou l&rsquo;application mobile SOMFY MyLink. Cette automatisation permet de g\u00e9rer facilement le toit r\u00e9tractable et <a href=\"https:\/\/ombrasole.com\/fr\/commercial\/rideaux-retractables-motorises-exterieur-tcl\/\">les rideaux motoris\u00e9s<\/a>, en adaptant l&rsquo;environnement en quelques secondes \u00e0 tous les besoins.\u00a0 De m\u00eame, la pergola commerciale Capriccio dispose d&rsquo;un syst\u00e8me de goutti\u00e8res int\u00e9gr\u00e9 qui g\u00e8re efficacement l&rsquo;eau de pluie.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1008\" height=\"756\" src=\"https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/1-Capriccio-pergola-retractable.jpg\" alt=\"Contr\u00f4le \u00e0 distance de la pergola commerciale avec l'application mobile SOMFY\" class=\"wp-image-4012\" srcset=\"https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/1-Capriccio-pergola-retractable.jpg 1008w, https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/1-Capriccio-pergola-retractable-300x225.jpg 300w, https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/1-Capriccio-pergola-retractable-768x576.jpg 768w\" sizes=\"auto, (max-width: 1008px) 100vw, 1008px\" \/><\/figure>\n\n\n\n<p><strong>3. Personnalisation totale pour s&rsquo;adapter \u00e0 votre marque<\/strong><\/p>\n\n\n\n<p>Capriccio est une <a href=\"https:\/\/ombrasole.com\/fr\/commercial\/auvents-de-terrasse-capriccio\/\">pergola modulaire<\/a> et personnalisable. Elle s&rsquo;adapte aux terrasses de toutes tailles, avec une projection allant jusqu&rsquo;\u00e0 24 pieds. Dans son design, vous pouvez incorporer ou modifier diff\u00e9rents \u00e9l\u00e9ments tels que :<\/p>\n\n\n\n<p>&#8211; Des lumi\u00e8res LED pour cr\u00e9er une ambiance<\/p>\n\n\n\n<p>&#8211; Chauffage pour les climats froids<\/p>\n\n\n\n<p>&#8211; Rideaux manuels ou motoris\u00e9s<\/p>\n\n\n\n<p>&#8211; Couleurs de la toile en vinyle<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Capriccio : bien plus qu&rsquo;une pergola<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"859\" height=\"690\" src=\"https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image-1.png\" alt=\"\" class=\"wp-image-4014\" srcset=\"https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image-1.png 859w, https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image-1-300x241.png 300w, https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image-1-768x617.png 768w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/figure>\n\n\n\n<p>Capriccio n&rsquo;est pas seulement une pergola r\u00e9tractable, c&rsquo;est un <a href=\"https:\/\/ombrasole.com\/fr\/blog\/3-facons-daugmenter-la-rentabilite-de-votre-restaurant-grace-a-lauvent-de-terrasse\/\">investissement<\/a> strat\u00e9gique pour toute entreprise qui souhaite maximiser l&rsquo;utilisation et l&rsquo;impact de ses espaces ext\u00e9rieurs. Con\u00e7ue pour s&rsquo;int\u00e9grer harmonieusement aux terrasses de restaurants, d&rsquo;h\u00f4tels, de rooftops ou de clubs, elle offre une combinaison parfaite d&rsquo;esth\u00e9tique, de fonctionnalit\u00e9 et de durabilit\u00e9.<\/p>\n\n\n\n<p>Gr\u00e2ce \u00e0 sa technologie avanc\u00e9e, sa conception modulaire et ses possibilit\u00e9s de personnalisation, <a href=\"https:\/\/ombrasole.com\/fr\/commercial\/auvents-de-terrasse-capriccio\/\">Capriccio<\/a> transforme n&rsquo;importe quelle terrasse en une extension <a href=\"https:\/\/ombrasole.com\/fr\/blog\/3-facons-daugmenter-la-rentabilite-de-votre-restaurant-grace-a-lauvent-de-terrasse\/\">rentable et accueillante de votre entreprise<\/a>, tout au long de l&rsquo;ann\u00e9e. Avec Ombrasole, vous ne vous contentez pas d&rsquo;installer une pergola : vous \u00e9levez l&rsquo;exp\u00e9rience de vos clients et le prestige de votre \u00e9tablissement.<\/p>\n\n\n\n<p><strong>Demandez un devis personnalis\u00e9<\/strong><\/p>\n\n\n\n<p>Vous \u00eates pr\u00eat \u00e0 transformer votre terrasse commerciale avec une <a href=\"https:\/\/ombrasole.com\/fr\/commercial\/auvents-de-terrasse-capriccio\/\">pergola r\u00e9tractable haute performance<\/a>?<\/p>\n\n\n\n<p>Contactez-nous d\u00e8s aujourd&rsquo;hui pour une <a href=\"https:\/\/ombrasole.com\/fr\/estimation-gratuite\/\">soumission gratuite<\/a> \u00e0 Montr\u00e9al et ses environs. Notre \u00e9quipe se fera un plaisir de vous accompagner tout au long du processus, de la conception \u00e0 l&rsquo;installation.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous souhaitez transformer la terrasse de votre entreprise en un espace \u00e9l\u00e9gant, confortable et prot\u00e9g\u00e9 tout au long de l&rsquo;ann\u00e9e?\u00a0 La pergola commerciale Capriccio, fabriqu\u00e9e \u00e0 Montr\u00e9al, est la meilleure solution pour les restaurants, les h\u00f4tels, les clubs de golf et les salles de r\u00e9ception qui souhaitent offrir une exp\u00e9rience ext\u00e9rieure de qualit\u00e9 sup\u00e9rieure sans&hellip;<\/p>\n","protected":false},"author":6,"featured_media":4010,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[29,40,33,34,31,41],"class_list":["post-4009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-auvent","tag-awning-2","tag-pergola-3","tag-restaurant","tag-retractable-2","tag-terrasse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec | Ombrasole Awnings<\/title>\n<meta name=\"description\" content=\"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec | Ombrasole Awnings\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec | Ombrasole Awnings\" \/>\n<meta property=\"og:description\" content=\"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec | Ombrasole Awnings\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/\" \/>\n<meta property=\"og:site_name\" content=\"Ombrasole Awnings\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ombrasole\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-05T13:12:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-05T14:42:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"902\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Valentina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valentina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\\\/\"},\"author\":{\"name\":\"Valentina\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#\\\/schema\\\/person\\\/35431a957ed3ca3e09362ef0a4ef8135\"},\"headline\":\"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec\",\"datePublished\":\"2025-05-05T13:12:24+00:00\",\"dateModified\":\"2025-05-05T14:42:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\\\/\"},\"wordCount\":541,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ombrasole.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image.png\",\"keywords\":[\"auvent\",\"awning\",\"pergola\",\"restaurant\",\"retractable\",\"terrasse\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\\\/\",\"url\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\\\/\",\"name\":\"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec | Ombrasole Awnings\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ombrasole.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image.png\",\"datePublished\":\"2025-05-05T13:12:24+00:00\",\"dateModified\":\"2025-05-05T14:42:16+00:00\",\"description\":\"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec | Ombrasole Awnings\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ombrasole.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image.png\",\"contentUrl\":\"https:\\\/\\\/ombrasole.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image.png\",\"width\":902,\"height\":678},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/\",\"name\":\"Ombrasole\",\"description\":\"Custom Made Awnings In Montreal, Our Style Makes The Difference\",\"publisher\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#organization\",\"name\":\"Ombrasole\",\"alternateName\":\"Ombrasole Awnings\",\"url\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ombrasole.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Ombrasole_logo_white.png\",\"contentUrl\":\"https:\\\/\\\/ombrasole.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Ombrasole_logo_white.png\",\"width\":328,\"height\":90,\"caption\":\"Ombrasole\"},\"image\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ombrasole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#\\\/schema\\\/person\\\/35431a957ed3ca3e09362ef0a4ef8135\",\"name\":\"Valentina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3ba829c24c1fedf9eed656f35ac3cd81026e1d3b05accd96bf38bc85f97a814?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3ba829c24c1fedf9eed656f35ac3cd81026e1d3b05accd96bf38bc85f97a814?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3ba829c24c1fedf9eed656f35ac3cd81026e1d3b05accd96bf38bc85f97a814?s=96&d=mm&r=g\",\"caption\":\"Valentina\"},\"url\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/author\\\/valentina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec | Ombrasole Awnings","description":"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec | Ombrasole Awnings","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/","og_locale":"fr_FR","og_type":"article","og_title":"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec | Ombrasole Awnings","og_description":"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec | Ombrasole Awnings","og_url":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/","og_site_name":"Ombrasole Awnings","article_publisher":"https:\/\/www.facebook.com\/ombrasole\/","article_published_time":"2025-05-05T13:12:24+00:00","article_modified_time":"2025-05-05T14:42:16+00:00","og_image":[{"width":902,"height":678,"url":"https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image.png","type":"image\/png"}],"author":"Valentina","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Valentina","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/#article","isPartOf":{"@id":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/"},"author":{"name":"Valentina","@id":"https:\/\/ombrasole.com\/fr\/#\/schema\/person\/35431a957ed3ca3e09362ef0a4ef8135"},"headline":"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec","datePublished":"2025-05-05T13:12:24+00:00","dateModified":"2025-05-05T14:42:16+00:00","mainEntityOfPage":{"@id":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/"},"wordCount":541,"commentCount":0,"publisher":{"@id":"https:\/\/ombrasole.com\/fr\/#organization"},"image":{"@id":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/#primaryimage"},"thumbnailUrl":"https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image.png","keywords":["auvent","awning","pergola","restaurant","retractable","terrasse"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/","url":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/","name":"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec | Ombrasole Awnings","isPartOf":{"@id":"https:\/\/ombrasole.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/#primaryimage"},"image":{"@id":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/#primaryimage"},"thumbnailUrl":"https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image.png","datePublished":"2025-05-05T13:12:24+00:00","dateModified":"2025-05-05T14:42:16+00:00","description":"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec | Ombrasole Awnings","breadcrumb":{"@id":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/#primaryimage","url":"https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image.png","contentUrl":"https:\/\/ombrasole.com\/wp-content\/uploads\/2025\/05\/image.png","width":902,"height":678},{"@type":"BreadcrumbList","@id":"https:\/\/ombrasole.com\/fr\/blog\/capriccio-la-meilleure-pergola-commerciale-retractable-pour-restaurants-hotels-et-terrasses-au-toit-quebec\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ombrasole.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Capriccio : La meilleure pergola commerciale r\u00e9tractable pour restaurants, h\u00f4tels et terrasses au toit, Qu\u00e9bec"}]},{"@type":"WebSite","@id":"https:\/\/ombrasole.com\/fr\/#website","url":"https:\/\/ombrasole.com\/fr\/","name":"Ombrasole","description":"Custom Made Awnings In Montreal, Our Style Makes The Difference","publisher":{"@id":"https:\/\/ombrasole.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ombrasole.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ombrasole.com\/fr\/#organization","name":"Ombrasole","alternateName":"Ombrasole Awnings","url":"https:\/\/ombrasole.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ombrasole.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ombrasole.com\/wp-content\/uploads\/2024\/01\/Ombrasole_logo_white.png","contentUrl":"https:\/\/ombrasole.com\/wp-content\/uploads\/2024\/01\/Ombrasole_logo_white.png","width":328,"height":90,"caption":"Ombrasole"},"image":{"@id":"https:\/\/ombrasole.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ombrasole\/"]},{"@type":"Person","@id":"https:\/\/ombrasole.com\/fr\/#\/schema\/person\/35431a957ed3ca3e09362ef0a4ef8135","name":"Valentina","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f3ba829c24c1fedf9eed656f35ac3cd81026e1d3b05accd96bf38bc85f97a814?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f3ba829c24c1fedf9eed656f35ac3cd81026e1d3b05accd96bf38bc85f97a814?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3ba829c24c1fedf9eed656f35ac3cd81026e1d3b05accd96bf38bc85f97a814?s=96&d=mm&r=g","caption":"Valentina"},"url":"https:\/\/ombrasole.com\/fr\/author\/valentina\/"}]}},"_links":{"self":[{"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/posts\/4009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/comments?post=4009"}],"version-history":[{"count":0,"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/posts\/4009\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/media\/4010"}],"wp:attachment":[{"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/media?parent=4009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/categories?post=4009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/tags?post=4009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}