{"id":1957,"date":"2024-01-20T21:02:34","date_gmt":"2024-01-20T21:02:34","guid":{"rendered":"https:\/\/ombrasole.wpenginepowered.com\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/"},"modified":"2024-03-01T19:13:34","modified_gmt":"2024-03-01T19:13:34","slug":"comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver","status":"publish","type":"post","link":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/","title":{"rendered":"Comment nettoyer la toile de votre auvent pendant l&rsquo;hiver ?"},"content":{"rendered":"\n<p>Afin d&rsquo;obtenir un auvent durable et bien entretenu, il est important de suivre quelques \u00e9tapes lorsque l&rsquo;auvent est utilis\u00e9 fr\u00e9quemment ainsi que juste avant les mois d&rsquo;hiver froids et enneig\u00e9s. Dans le prolongement de notre blog pr\u00e9c\u00e9dent, Entretien et nettoyage faciles des toiles de store en acrylique, nous d\u00e9veloppons le sujet de l&rsquo;entretien de vos toiles de store et partageons les \u00e9tapes et t\u00e2ches n\u00e9cessaires pour un entretien optimal avant le d\u00e9but de l&rsquo;hiver, lorsqu&rsquo;il est temps de fermer vos stores r\u00e9tractables. (Pour savoir si votre store peut \u00eatre utilis\u00e9 en hiver, lisez notre article pr\u00e9c\u00e9dent ici).<\/p>\n\n<p>Chez OmbraSole, nous utilisons les derniers tissus acryliques Sunbrella qui sont tr\u00e8s faciles \u00e0 entretenir, sans l&rsquo;aide d&rsquo;un professionnel.<\/p>\n\n<h3 class=\"wp-block-heading\">Des soins appropri\u00e9s tout au long de l&rsquo;ann\u00e9e<\/h3>\n\n<p>Voici les mesures que les propri\u00e9taires peuvent prendre pour l&rsquo;entretenir correctement tout au long de l&rsquo;ann\u00e9e :<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Pendant les mois les plus chauds, il est important de nettoyer la toile chaque semaine. Si cette op\u00e9ration n&rsquo;est pas effectu\u00e9e r\u00e9guli\u00e8rement (de pr\u00e9f\u00e9rence une fois par semaine, en cas d&rsquo;utilisation fr\u00e9quente), la poussi\u00e8re et la salet\u00e9 s&rsquo;incrusteront dans le tissu et il sera beaucoup plus difficile de le nettoyer par la suite. Apr\u00e8s de nombreuses ann\u00e9es d&rsquo;utilisation, la toile peut avoir besoin d&rsquo;un nettoyage plus approfondi effectu\u00e9 par une entreprise de nettoyage sp\u00e9cialis\u00e9e.<\/li>\n\n\n\n<li>Au moment de nettoyer votre auvent avec un service de nettoyage sp\u00e9cialis\u00e9, il est essentiel de demander qu&rsquo;il imperm\u00e9abilise la toile en m\u00eame temps, car les produits utilis\u00e9s pour le nettoyage peuvent enlever la protection de la toiture (hydrofuge).<\/li>\n\n\n\n<li>Lorsque l&rsquo;hiver arrive et que vous venez d&rsquo;arroser votre store avec un tuyau d&rsquo;arrosage pour la derni\u00e8re fois avant l&rsquo;arriv\u00e9e du froid, il est important de le s\u00e9cher imm\u00e9diatement. Si la toile reste humide alors qu&rsquo;elle est enroul\u00e9e tout l&rsquo;hiver, des champignons commenceront rapidement \u00e0 pousser sur le tissu. \u00c0 ce moment-l\u00e0, il sera extr\u00eamement difficile et fastidieux de les enlever vous-m\u00eame et vous devrez probablement faire appel \u00e0 une entreprise de nettoyage sp\u00e9cialis\u00e9e.<\/li>\n<\/ol>\n\n<p>Cependant, pendant les mois les plus chauds, vous pouvez enrouler votre store mouill\u00e9, car il est plus probable que vous l&rsquo;ouvriez le lendemain et qu&rsquo;il s\u00e8che sous le soleil chaud.<\/p>\n\n<h3 class=\"wp-block-heading\">Pourquoi les toits des auvents sont-ils si sales ?<\/h3>\n\n<p>Les auvents se salissent en raison de la pollution environnante et de la formation de moisissures. Bien entendu, si le propri\u00e9taire vit \u00e0 proximit\u00e9 d&rsquo;une autoroute, d&rsquo;une route ou d&rsquo;une usine tr\u00e8s fr\u00e9quent\u00e9e, ou s&rsquo;il est entour\u00e9 d&rsquo;arbres et d&rsquo;oiseaux, la toile du store se salira beaucoup plus rapidement. Voici comment faire en sorte que votre auvent reste propre et en bon \u00e9tat, quel que soit l&rsquo;endroit o\u00f9 vous vivez :<\/p>\n\n<p>Pour nettoyer la toile acrylique, il n&rsquo;est pas n\u00e9cessaire de la d\u00e9monter ; il suffit d&rsquo;installer un tabouret stable ou une \u00e9chelle et de la placer pr\u00e8s de l&rsquo;auvent.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Vous pouvez commencer par d\u00e9poussi\u00e9rer votre toile \u00e0 l&rsquo;aide d&rsquo;un aspirateur.<\/li>\n\n\n\n<li>Rincez ensuite une partie de la salet\u00e9 avec de l&rsquo;eau.<\/li>\n\n\n\n<li>Apr\u00e8s avoir rinc\u00e9 rapidement la toile, vous pouvez m\u00e9langer votre savon avec de l&rsquo;eau. Le savon utilis\u00e9 doit \u00eatre tr\u00e8s doux et incolore avec un PH neutre.<\/li>\n\n\n\n<li>Appliquer le savon \u00e0 l&rsquo;aide d&rsquo;une brosse douce, en insistant sur les taches visibles.<\/li>\n\n\n\n<li>Rincez les r\u00e9sidus de savon avec votre tuyau d&rsquo;arrosage.<\/li>\n\n\n\n<li>Ne refermez PAS l&rsquo;auvent imm\u00e9diatement apr\u00e8s l&rsquo;avoir lav\u00e9 au jet d&rsquo;eau ; laissez la toile s\u00e9cher pour ne pas cr\u00e9er de nouvelles taches et de la moisissure.<\/li>\n<\/ul>\n\n<p>Il est important de noter que lors du nettoyage de votre store, les produits suivants ne doivent absolument pas \u00eatre utilis\u00e9s, car ils peuvent endommager la toile et les capacit\u00e9s de filtrage peuvent \u00eatre affaiblies :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>un jet d&rsquo;eau \u00e0 haute pression,<\/li>\n\n\n\n<li>un pinceau rigide,<\/li>\n\n\n\n<li>l&rsquo;eau de Javel,<\/li>\n\n\n\n<li>un g\u00e9n\u00e9rateur de vapeur.<\/li>\n<\/ul>\n\n<p>Pour plus d&rsquo;informations sur le nettoyage et l&rsquo;entretien de votre store, contactez-nous d\u00e8s aujourd&rsquo;hui.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Afin d&rsquo;obtenir un auvent durable et bien entretenu, il est important de suivre quelques \u00e9tapes lorsque l&rsquo;auvent est utilis\u00e9 fr\u00e9quemment ainsi que juste avant les mois d&rsquo;hiver froids et enneig\u00e9s.<\/p>\n","protected":false},"author":1,"featured_media":1137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment nettoyer la toile de votre auvent pendant l&#039;hiver ? | Ombrasole Awnings<\/title>\n<meta name=\"description\" content=\"Comment nettoyer la toile de votre auvent pendant l&#039;hiver ? | Ombrasole Awnings\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment nettoyer la toile de votre auvent pendant l&#039;hiver ? | Ombrasole Awnings\" \/>\n<meta property=\"og:description\" content=\"Comment nettoyer la toile de votre auvent pendant l&#039;hiver ? | Ombrasole Awnings\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/\" \/>\n<meta property=\"og:site_name\" content=\"Ombrasole Awnings\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ombrasole\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-20T21:02:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-01T19:13:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ombrasole.com\/wp-content\/uploads\/2024\/01\/Custom-Made-Garden-Furniture-Montreal-1-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ombrasolestg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ombrasolestg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\\\/\"},\"author\":{\"name\":\"ombrasolestg\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#\\\/schema\\\/person\\\/f994e3b27d80a15e3c369d7884a4a7cd\"},\"headline\":\"Comment nettoyer la toile de votre auvent pendant l&rsquo;hiver ?\",\"datePublished\":\"2024-01-20T21:02:34+00:00\",\"dateModified\":\"2024-03-01T19:13:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\\\/\"},\"wordCount\":741,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ombrasole.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Custom-Made-Garden-Furniture-Montreal-1.png\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\\\/\",\"url\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\\\/\",\"name\":\"Comment nettoyer la toile de votre auvent pendant l'hiver ? | Ombrasole Awnings\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ombrasole.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Custom-Made-Garden-Furniture-Montreal-1.png\",\"datePublished\":\"2024-01-20T21:02:34+00:00\",\"dateModified\":\"2024-03-01T19:13:34+00:00\",\"description\":\"Comment nettoyer la toile de votre auvent pendant l'hiver ? | Ombrasole Awnings\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ombrasole.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Custom-Made-Garden-Furniture-Montreal-1.png\",\"contentUrl\":\"https:\\\/\\\/ombrasole.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Custom-Made-Garden-Furniture-Montreal-1.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/blog\\\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment nettoyer la toile de votre auvent pendant l&#8217;hiver ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/\",\"name\":\"Ombrasole\",\"description\":\"Custom Made Awnings In Montreal, Our Style Makes The Difference\",\"publisher\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#organization\",\"name\":\"Ombrasole\",\"alternateName\":\"Ombrasole Awnings\",\"url\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ombrasole.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Ombrasole_logo_white.png\",\"contentUrl\":\"https:\\\/\\\/ombrasole.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Ombrasole_logo_white.png\",\"width\":328,\"height\":90,\"caption\":\"Ombrasole\"},\"image\":{\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ombrasole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/#\\\/schema\\\/person\\\/f994e3b27d80a15e3c369d7884a4a7cd\",\"name\":\"ombrasolestg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09e519588a345fbb9613659975af644d226ada37a9f628400fc6a33f3713d08a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09e519588a345fbb9613659975af644d226ada37a9f628400fc6a33f3713d08a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09e519588a345fbb9613659975af644d226ada37a9f628400fc6a33f3713d08a?s=96&d=mm&r=g\",\"caption\":\"ombrasolestg\"},\"sameAs\":[\"https:\\\/\\\/ombrasole.com\"],\"url\":\"https:\\\/\\\/ombrasole.com\\\/fr\\\/author\\\/ombrasolestg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment nettoyer la toile de votre auvent pendant l'hiver ? | Ombrasole Awnings","description":"Comment nettoyer la toile de votre auvent pendant l'hiver ? | Ombrasole Awnings","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment nettoyer la toile de votre auvent pendant l'hiver ? | Ombrasole Awnings","og_description":"Comment nettoyer la toile de votre auvent pendant l'hiver ? | Ombrasole Awnings","og_url":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/","og_site_name":"Ombrasole Awnings","article_publisher":"https:\/\/www.facebook.com\/ombrasole\/","article_published_time":"2024-01-20T21:02:34+00:00","article_modified_time":"2024-03-01T19:13:34+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/ombrasole.com\/wp-content\/uploads\/2024\/01\/Custom-Made-Garden-Furniture-Montreal-1-1024x576.png","type":"image\/png"}],"author":"ombrasolestg","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"ombrasolestg","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/#article","isPartOf":{"@id":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/"},"author":{"name":"ombrasolestg","@id":"https:\/\/ombrasole.com\/fr\/#\/schema\/person\/f994e3b27d80a15e3c369d7884a4a7cd"},"headline":"Comment nettoyer la toile de votre auvent pendant l&rsquo;hiver ?","datePublished":"2024-01-20T21:02:34+00:00","dateModified":"2024-03-01T19:13:34+00:00","mainEntityOfPage":{"@id":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/"},"wordCount":741,"commentCount":0,"publisher":{"@id":"https:\/\/ombrasole.com\/fr\/#organization"},"image":{"@id":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/#primaryimage"},"thumbnailUrl":"https:\/\/ombrasole.com\/wp-content\/uploads\/2024\/01\/Custom-Made-Garden-Furniture-Montreal-1.png","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/","url":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/","name":"Comment nettoyer la toile de votre auvent pendant l'hiver ? | Ombrasole Awnings","isPartOf":{"@id":"https:\/\/ombrasole.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/#primaryimage"},"image":{"@id":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/#primaryimage"},"thumbnailUrl":"https:\/\/ombrasole.com\/wp-content\/uploads\/2024\/01\/Custom-Made-Garden-Furniture-Montreal-1.png","datePublished":"2024-01-20T21:02:34+00:00","dateModified":"2024-03-01T19:13:34+00:00","description":"Comment nettoyer la toile de votre auvent pendant l'hiver ? | Ombrasole Awnings","breadcrumb":{"@id":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/#primaryimage","url":"https:\/\/ombrasole.com\/wp-content\/uploads\/2024\/01\/Custom-Made-Garden-Furniture-Montreal-1.png","contentUrl":"https:\/\/ombrasole.com\/wp-content\/uploads\/2024\/01\/Custom-Made-Garden-Furniture-Montreal-1.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/ombrasole.com\/fr\/blog\/comment-nettoyer-la-toile-de-votre-auvent-pendant-lhiver\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ombrasole.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment nettoyer la toile de votre auvent pendant l&#8217;hiver ?"}]},{"@type":"WebSite","@id":"https:\/\/ombrasole.com\/fr\/#website","url":"https:\/\/ombrasole.com\/fr\/","name":"Ombrasole","description":"Custom Made Awnings In Montreal, Our Style Makes The Difference","publisher":{"@id":"https:\/\/ombrasole.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ombrasole.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ombrasole.com\/fr\/#organization","name":"Ombrasole","alternateName":"Ombrasole Awnings","url":"https:\/\/ombrasole.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ombrasole.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ombrasole.com\/wp-content\/uploads\/2024\/01\/Ombrasole_logo_white.png","contentUrl":"https:\/\/ombrasole.com\/wp-content\/uploads\/2024\/01\/Ombrasole_logo_white.png","width":328,"height":90,"caption":"Ombrasole"},"image":{"@id":"https:\/\/ombrasole.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ombrasole\/"]},{"@type":"Person","@id":"https:\/\/ombrasole.com\/fr\/#\/schema\/person\/f994e3b27d80a15e3c369d7884a4a7cd","name":"ombrasolestg","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/09e519588a345fbb9613659975af644d226ada37a9f628400fc6a33f3713d08a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/09e519588a345fbb9613659975af644d226ada37a9f628400fc6a33f3713d08a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/09e519588a345fbb9613659975af644d226ada37a9f628400fc6a33f3713d08a?s=96&d=mm&r=g","caption":"ombrasolestg"},"sameAs":["https:\/\/ombrasole.com"],"url":"https:\/\/ombrasole.com\/fr\/author\/ombrasolestg\/"}]}},"_links":{"self":[{"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/posts\/1957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/comments?post=1957"}],"version-history":[{"count":0,"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/posts\/1957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/media\/1137"}],"wp:attachment":[{"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/media?parent=1957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/categories?post=1957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ombrasole.com\/fr\/wp-json\/wp\/v2\/tags?post=1957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}